{"id":7486,"date":"2024-09-24T09:33:16","date_gmt":"2024-09-24T07:33:16","guid":{"rendered":"https:\/\/trickshot.ro\/?page_id=7486"},"modified":"2026-03-24T20:35:42","modified_gmt":"2026-03-24T18:35:42","slug":"meniu-food-afi-cotroceni","status":"publish","type":"page","link":"https:\/\/trickshot.ro\/en\/meniu-food-afi-cotroceni\/","title":{"rendered":"Meniu Food Afi Cotroceni"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><div class=\"vc_row wpb_row vc_row-fluid banner_categorii_meniu vc_custom_1666170353330 vc_row-has-fill\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_raw_code wpb_raw_html wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<div class=\"ban_cat_wrap\">\n <img decoding=\"async\" src=\"https:\/\/trickshot.ro\/wp-content\/uploads\/2022\/10\/bannere-categorii1.png\" width:750px alt=\"banner categorii food\">\n<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid vc_custom_1713860256164 vc_row-has-fill\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element menu_category_food_desc\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p style=\"padding-left: 0px!important;\"><span style=\"font-weight: 600;\"> \ud83c\udf31Responsabilitate fa\u021b\u0103 de m\u00e2ncare:<\/span><br \/>\n1\/3 din m\u00e2ncarea produs\u0103 \u00een lume este irosit\u0103.<br \/>\nAsta \u00eenseamn\u0103 peste 1,3 miliarde de tone de alimente \u00een fiecare an.<br \/>\n\u00cen Rom\u00e2nia, risipa alimentar\u0103 dep\u0103\u0219e\u0219te 2,2 milioane de tone anual, aproximativ 129 kg de m\u00e2ncare irosit\u0103 de fiecare persoan\u0103 \u00een fiecare an.<br \/>\nLa TRICKSHOT credem c\u0103 m\u00e2ncarea merit\u0103 respectat\u0103.<\/p>\n<p style=\"margin: 10px 0; padding-left: 0px!important;\"><span style=\"font-weight: 600;\"><i class=\"fa-regular fa-square-check\" style=\"color: #2adf57;\"><\/i> Comand\u0103 responsabil<\/span><br \/>\nAlege preparatele \u00een func\u021bie de c\u00e2t \u00ee\u021bi dore\u0219ti s\u0103 consumi.<\/p>\n<p style=\"padding-left: 0px!important;\"><span style=\"font-weight: 600;\"><i class=\"fa-regular fa-square-check\" style=\"color: #2adf57;\"><\/i> Solicit\u0103 la pachet ce r\u0103m\u00e2ne<\/span><br \/>\nDac\u0103 nu ai terminat preparatul, te rug\u0103m s\u0103 ne spui \u0219i \u00eel vom preg\u0103ti pentru pachet.<br \/>\n\u00cempreun\u0103 putem reduce risipa alimentar\u0103.<br \/>\n<strong>#fiiresponsabil<\/strong><\/p>\n<p><span style=\"font-size: 14px; font-style: italic;\">*Date bazate pe rapoarte publicate de Food and Agriculture Organization, Eurostat \u0219i estim\u0103ri privind risipa alimentar\u0103 \u00een Rom\u00e2nia publicate de Ministerul Mediului, Apelor \u0219i P\u0103durilor.<\/span><\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid product_wrapper vc_custom_1665746721991 vc_row-has-fill\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_left wpb_content_element  extend_img\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper   vc_box_border_grey\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"900\" src=\"https:\/\/trickshot.ro\/wp-content\/uploads\/2026\/03\/Breakfast-O-clock_16x9.webp\" class=\"vc_single_image-img attachment-full\" alt=\"\" title=\"Breakfast O clock_16x9\" srcset=\"https:\/\/trickshot.ro\/wp-content\/uploads\/2026\/03\/Breakfast-O-clock_16x9.webp 1600w, https:\/\/trickshot.ro\/wp-content\/uploads\/2026\/03\/Breakfast-O-clock_16x9-300x169.webp 300w, https:\/\/trickshot.ro\/wp-content\/uploads\/2026\/03\/Breakfast-O-clock_16x9-1024x576.webp 1024w, https:\/\/trickshot.ro\/wp-content\/uploads\/2026\/03\/Breakfast-O-clock_16x9-768x432.webp 768w, https:\/\/trickshot.ro\/wp-content\/uploads\/2026\/03\/Breakfast-O-clock_16x9-1536x864.webp 1536w, https:\/\/trickshot.ro\/wp-content\/uploads\/2026\/03\/Breakfast-O-clock_16x9-18x10.webp 18w\" sizes=\"auto, (max-width: 1600px) 100vw, 1600px\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n<div class=\"vc_row wpb_row vc_inner vc_row-fluid vc_custom_1666254605615 vc_row-has-fill\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h2 style=\"font-size: 26px; text-align: center;\"><strong>BREAKFAST O&#8217;CLOCK<\/strong><\/h2>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div>\n\t<div class=\"wpb_text_column wpb_content_element menu_category_food_desc\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p style=\"text-align: center; font-weight: 600;\">Luni \u2013 Vineri | 09:00 \u2013 12:00<br \/>\nS\u00e2mb\u0103t\u0103 \u2013 Duminic\u0103 | 09:00 \u2013 14:00<\/p>\n\n\t\t<\/div>\n\t<\/div>\n<div class=\"vc_empty_space\"   style=\"height: 22px\"><span class=\"vc_empty_space_inner\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid product_wrapper vc_custom_1660494354190 vc_row-has-fill\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_left wpb_content_element  extend_img\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper   vc_box_border_grey\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"900\" src=\"https:\/\/trickshot.ro\/wp-content\/uploads\/2024\/06\/SoupsCreams.webp\" class=\"vc_single_image-img attachment-full\" alt=\"\" title=\"Soups&amp;Creams\" srcset=\"https:\/\/trickshot.ro\/wp-content\/uploads\/2024\/06\/SoupsCreams.webp 1600w, https:\/\/trickshot.ro\/wp-content\/uploads\/2024\/06\/SoupsCreams-300x169.webp 300w, https:\/\/trickshot.ro\/wp-content\/uploads\/2024\/06\/SoupsCreams-1024x576.webp 1024w, https:\/\/trickshot.ro\/wp-content\/uploads\/2024\/06\/SoupsCreams-768x432.webp 768w, https:\/\/trickshot.ro\/wp-content\/uploads\/2024\/06\/SoupsCreams-1536x864.webp 1536w, https:\/\/trickshot.ro\/wp-content\/uploads\/2024\/06\/SoupsCreams-18x10.webp 18w\" sizes=\"auto, (max-width: 1600px) 100vw, 1600px\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n<div class=\"vc_row wpb_row vc_inner vc_row-fluid vc_custom_1666254638284 vc_row-has-fill\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h2 style=\"font-size: 26px; text-align: center;\"><strong>SOUPS &amp; CREAMS<\/strong><\/h2>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div>\n\t<div class=\"wpb_text_column wpb_content_element menu_category_food_desc\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p style=\"text-align: center;\">PREPARATELE SUNT DISPONIBILE \u00ceNCEP\u00c2ND CU ORA 12:00<\/p>\n\n\t\t<\/div>\n\t<\/div>\n<div class=\"vc_empty_space\"   style=\"height: 22px\"><span class=\"vc_empty_space_inner\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid product_wrapper vc_custom_1660494354190 vc_row-has-fill\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_left wpb_content_element  extend_img\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper   vc_box_border_grey\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"533\" src=\"https:\/\/trickshot.ro\/wp-content\/uploads\/2025\/10\/Yummy-to-share-800.webp\" class=\"vc_single_image-img attachment-full\" alt=\"\" title=\"Yummy-to-share-800\" srcset=\"https:\/\/trickshot.ro\/wp-content\/uploads\/2025\/10\/Yummy-to-share-800.webp 800w, https:\/\/trickshot.ro\/wp-content\/uploads\/2025\/10\/Yummy-to-share-800-300x200.webp 300w, https:\/\/trickshot.ro\/wp-content\/uploads\/2025\/10\/Yummy-to-share-800-768x512.webp 768w, https:\/\/trickshot.ro\/wp-content\/uploads\/2025\/10\/Yummy-to-share-800-18x12.webp 18w, https:\/\/trickshot.ro\/wp-content\/uploads\/2025\/10\/Yummy-to-share-800-360x240.webp 360w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n<div class=\"vc_row wpb_row vc_inner vc_row-fluid vc_custom_1666254652486 vc_row-has-fill\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h2 style=\"font-size: 26px; text-align: center;\"><strong>YUMMY-DISHES TO SHARE<\/strong><\/h2>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div>\n\t<div class=\"wpb_text_column wpb_content_element menu_category_food_desc\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p style=\"text-align: center;\">PREPARATELE SUNT DISPONIBILE \u00ceNCEP\u00c2ND CU ORA 12:00<\/p>\n\n\t\t<\/div>\n\t<\/div>\n<div class=\"vc_empty_space\"   style=\"height: 22px\"><span class=\"vc_empty_space_inner\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid product_wrapper vc_custom_1660494354190 vc_row-has-fill\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_left wpb_content_element  extend_img\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper   vc_box_border_grey\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"900\" src=\"https:\/\/trickshot.ro\/wp-content\/uploads\/2024\/06\/Keep-it-light.webp\" class=\"vc_single_image-img attachment-full\" alt=\"\" title=\"Keep it light\" srcset=\"https:\/\/trickshot.ro\/wp-content\/uploads\/2024\/06\/Keep-it-light.webp 1600w, https:\/\/trickshot.ro\/wp-content\/uploads\/2024\/06\/Keep-it-light-300x169.webp 300w, https:\/\/trickshot.ro\/wp-content\/uploads\/2024\/06\/Keep-it-light-1024x576.webp 1024w, https:\/\/trickshot.ro\/wp-content\/uploads\/2024\/06\/Keep-it-light-768x432.webp 768w, https:\/\/trickshot.ro\/wp-content\/uploads\/2024\/06\/Keep-it-light-1536x864.webp 1536w, https:\/\/trickshot.ro\/wp-content\/uploads\/2024\/06\/Keep-it-light-18x10.webp 18w\" sizes=\"auto, (max-width: 1600px) 100vw, 1600px\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n<div class=\"vc_row wpb_row vc_inner vc_row-fluid vc_custom_1666254688231 vc_row-has-fill\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h2 style=\"font-size: 26px; text-align: center;\"><strong>FRESH SALADS &amp; MORE<\/strong><\/h2>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div>\n\t<div class=\"wpb_text_column wpb_content_element menu_category_food_desc\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p style=\"text-align: center;\">PREPARATELE SUNT DISPONIBILE \u00ceNCEP\u00c2ND CU ORA 12:00<\/p>\n\n\t\t<\/div>\n\t<\/div>\n<div class=\"vc_empty_space\"   style=\"height: 22px\"><span class=\"vc_empty_space_inner\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid product_wrapper vc_custom_1660494354190 vc_row-has-fill\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_left wpb_content_element  extend_img\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper   vc_box_border_grey\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"900\" src=\"https:\/\/trickshot.ro\/wp-content\/uploads\/2026\/03\/pasta_16x9.webp\" class=\"vc_single_image-img attachment-full\" alt=\"\" title=\"pasta_16x9\" srcset=\"https:\/\/trickshot.ro\/wp-content\/uploads\/2026\/03\/pasta_16x9.webp 1600w, https:\/\/trickshot.ro\/wp-content\/uploads\/2026\/03\/pasta_16x9-300x169.webp 300w, https:\/\/trickshot.ro\/wp-content\/uploads\/2026\/03\/pasta_16x9-1024x576.webp 1024w, https:\/\/trickshot.ro\/wp-content\/uploads\/2026\/03\/pasta_16x9-768x432.webp 768w, https:\/\/trickshot.ro\/wp-content\/uploads\/2026\/03\/pasta_16x9-1536x864.webp 1536w, https:\/\/trickshot.ro\/wp-content\/uploads\/2026\/03\/pasta_16x9-18x10.webp 18w\" sizes=\"auto, (max-width: 1600px) 100vw, 1600px\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n<div class=\"vc_row wpb_row vc_inner vc_row-fluid vc_custom_1666254710225 vc_row-has-fill\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h2 style=\"font-size: 26px; text-align: center;\"><strong>PASTA &amp; RISOTTO<\/strong><\/h2>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div>\n\t<div class=\"wpb_text_column wpb_content_element menu_category_food_desc\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p style=\"text-align: center;\">PREPARATELE SUNT DISPONIBILE \u00ceNCEP\u00c2ND CU ORA 12:00<\/p>\n\n\t\t<\/div>\n\t<\/div>\n<div class=\"vc_empty_space\"   style=\"height: 22px\"><span class=\"vc_empty_space_inner\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid product_wrapper vc_custom_1660494354190 vc_row-has-fill\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_left wpb_content_element  extend_img\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper   vc_box_border_grey\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"563\" src=\"https:\/\/trickshot.ro\/wp-content\/uploads\/2024\/10\/Josper_Adana-kebab-nepicant.webp\" class=\"vc_single_image-img attachment-full\" alt=\"Josper_Adana kebab nepicant\" title=\"Josper_Adana kebab nepicant\" srcset=\"https:\/\/trickshot.ro\/wp-content\/uploads\/2024\/10\/Josper_Adana-kebab-nepicant.webp 1000w, https:\/\/trickshot.ro\/wp-content\/uploads\/2024\/10\/Josper_Adana-kebab-nepicant-300x169.webp 300w, https:\/\/trickshot.ro\/wp-content\/uploads\/2024\/10\/Josper_Adana-kebab-nepicant-768x432.webp 768w, https:\/\/trickshot.ro\/wp-content\/uploads\/2024\/10\/Josper_Adana-kebab-nepicant-18x10.webp 18w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n<div class=\"vc_row wpb_row vc_inner vc_row-fluid vc_custom_1666254720877 vc_row-has-fill\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h2 style=\"font-size: 26px; text-align: center;\"><strong>FROM OUR JOSPER GRILL<\/strong><\/h2>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div>\n\t<div class=\"wpb_text_column wpb_content_element menu_category_food_desc\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p style=\"text-align: center;\">THE <strong>JOSPER GRILL<\/strong> IS A HIGH-END CHARCOAL OVEN AND GRILL THAT COMBINES THE FUNCTIONALITY OF A TRADITIONAL GRILL WITH THE BENEFITS OF AN OVEN. ORIGINALLY DEVELOPED IN SPAIN, IT\u2019S KNOWN FOR ITS ABILITY TO COOK FOOD AT HIGH TEMPERATURES WHILE IMPARTING A DISTINCT SMOKY FLAVOR. IS CELEBRATED FOR ENHANCING THE NATURAL FLAVORS OF FOOD AND PROVIDING A UNIQUE DINING EXPERIENCE THAT COMBINES TRADITION WITH MODERN COOKING TECHNIQ<\/p>\n\n\t\t<\/div>\n\t<\/div>\n<div class=\"vc_empty_space\"   style=\"height: 22px\"><span class=\"vc_empty_space_inner\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid product_wrapper vc_custom_1660494354190 vc_row-has-fill\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_left wpb_content_element  extend_img\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper   vc_box_border_grey\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"900\" src=\"https:\/\/trickshot.ro\/wp-content\/uploads\/2026\/03\/Smashed-Burger_dark-BG.webp\" class=\"vc_single_image-img attachment-full\" alt=\"\" title=\"Smashed-Burger_dark-BG\" srcset=\"https:\/\/trickshot.ro\/wp-content\/uploads\/2026\/03\/Smashed-Burger_dark-BG.webp 1600w, https:\/\/trickshot.ro\/wp-content\/uploads\/2026\/03\/Smashed-Burger_dark-BG-300x169.webp 300w, https:\/\/trickshot.ro\/wp-content\/uploads\/2026\/03\/Smashed-Burger_dark-BG-1024x576.webp 1024w, https:\/\/trickshot.ro\/wp-content\/uploads\/2026\/03\/Smashed-Burger_dark-BG-768x432.webp 768w, https:\/\/trickshot.ro\/wp-content\/uploads\/2026\/03\/Smashed-Burger_dark-BG-1536x864.webp 1536w, https:\/\/trickshot.ro\/wp-content\/uploads\/2026\/03\/Smashed-Burger_dark-BG-18x10.webp 18w\" sizes=\"auto, (max-width: 1600px) 100vw, 1600px\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n<div class=\"vc_row wpb_row vc_inner vc_row-fluid vc_custom_1666254720877 vc_row-has-fill\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h2 style=\"font-size: 26px; text-align: center;\"><strong>BURGERS<\/strong><\/h2>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div>\n\t<div class=\"wpb_text_column wpb_content_element menu_category_food_desc\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p style=\"text-align: center;\">PREPARATELE SUNT DISPONIBILE \u00ceNCEP\u00c2ND CU ORA 12:00<\/p>\n\n\t\t<\/div>\n\t<\/div>\n<div class=\"vc_empty_space\"   style=\"height: 22px\"><span class=\"vc_empty_space_inner\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid product_wrapper vc_custom_1660494354190 vc_row-has-fill\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_left wpb_content_element  extend_img\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper   vc_box_border_grey\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"900\" src=\"https:\/\/trickshot.ro\/wp-content\/uploads\/2026\/03\/Pizza-Diavola_dark-BG_01.webp\" class=\"vc_single_image-img attachment-full\" alt=\"\" title=\"Pizza-Diavola_dark-BG_01\" srcset=\"https:\/\/trickshot.ro\/wp-content\/uploads\/2026\/03\/Pizza-Diavola_dark-BG_01.webp 1200w, https:\/\/trickshot.ro\/wp-content\/uploads\/2026\/03\/Pizza-Diavola_dark-BG_01-300x225.webp 300w, https:\/\/trickshot.ro\/wp-content\/uploads\/2026\/03\/Pizza-Diavola_dark-BG_01-1024x768.webp 1024w, https:\/\/trickshot.ro\/wp-content\/uploads\/2026\/03\/Pizza-Diavola_dark-BG_01-768x576.webp 768w, https:\/\/trickshot.ro\/wp-content\/uploads\/2026\/03\/Pizza-Diavola_dark-BG_01-16x12.webp 16w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n<div class=\"vc_row wpb_row vc_inner vc_row-fluid vc_custom_1666254727519 vc_row-has-fill\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h2 style=\"font-size: 26px; text-align: center;\"><strong>ROMAN PIZZA \/ CRUNCHY CRUST<\/strong><\/h2>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div>\n\t<div class=\"wpb_text_column wpb_content_element menu_category_food_desc\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p style=\"text-align: center;\">PREPARATELE SUNT DISPONIBILE \u00ceNCEP\u00c2ND CU ORA 12:00<\/p>\n\n\t\t<\/div>\n\t<\/div>\n<div class=\"vc_empty_space\"   style=\"height: 22px\"><span class=\"vc_empty_space_inner\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid product_wrapper vc_custom_1660494354190 vc_row-has-fill\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_left wpb_content_element  extend_img\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper   vc_box_border_grey\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"900\" src=\"https:\/\/trickshot.ro\/wp-content\/uploads\/2024\/06\/Meet-the-Fisherman.webp\" class=\"vc_single_image-img attachment-full\" alt=\"\" title=\"Meet the Fisherman\" srcset=\"https:\/\/trickshot.ro\/wp-content\/uploads\/2024\/06\/Meet-the-Fisherman.webp 1600w, https:\/\/trickshot.ro\/wp-content\/uploads\/2024\/06\/Meet-the-Fisherman-300x169.webp 300w, https:\/\/trickshot.ro\/wp-content\/uploads\/2024\/06\/Meet-the-Fisherman-1024x576.webp 1024w, https:\/\/trickshot.ro\/wp-content\/uploads\/2024\/06\/Meet-the-Fisherman-768x432.webp 768w, https:\/\/trickshot.ro\/wp-content\/uploads\/2024\/06\/Meet-the-Fisherman-1536x864.webp 1536w, https:\/\/trickshot.ro\/wp-content\/uploads\/2024\/06\/Meet-the-Fisherman-18x10.webp 18w\" sizes=\"auto, (max-width: 1600px) 100vw, 1600px\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n<div class=\"vc_row wpb_row vc_inner vc_row-fluid vc_custom_1666254699273 vc_row-has-fill\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h2 style=\"font-size: 26px; text-align: center;\"><strong>CHEF&#8217;S CHOICE<\/strong><\/h2>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div>\n\t<div class=\"wpb_text_column wpb_content_element menu_category_food_desc\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p style=\"text-align: center;\">PREPARATELE SUNT DISPONIBILE \u00ceNCEP\u00c2ND CU ORA 12:00<\/p>\n\n\t\t<\/div>\n\t<\/div>\n<div class=\"vc_empty_space\"   style=\"height: 22px\"><span class=\"vc_empty_space_inner\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid product_wrapper vc_custom_1660494354190 vc_row-has-fill\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_left wpb_content_element  extend_img\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper   vc_box_border_grey\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"563\" src=\"https:\/\/trickshot.ro\/wp-content\/uploads\/2024\/10\/side_dish.webp\" class=\"vc_single_image-img attachment-full\" alt=\"side_dish\" title=\"side_dish\" srcset=\"https:\/\/trickshot.ro\/wp-content\/uploads\/2024\/10\/side_dish.webp 1000w, https:\/\/trickshot.ro\/wp-content\/uploads\/2024\/10\/side_dish-300x169.webp 300w, https:\/\/trickshot.ro\/wp-content\/uploads\/2024\/10\/side_dish-768x432.webp 768w, https:\/\/trickshot.ro\/wp-content\/uploads\/2024\/10\/side_dish-18x10.webp 18w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n<div class=\"vc_row wpb_row vc_inner vc_row-fluid vc_custom_1666254747945 vc_row-has-fill\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h2 style=\"font-size: 26px; text-align: center;\"><strong>SIDE DISHES<\/strong><\/h2>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div>\n\t<div class=\"wpb_text_column wpb_content_element menu_category_food_desc\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p style=\"text-align: center;\">PREPARATELE SUNT DISPONIBILE \u00ceNCEP\u00c2ND CU ORA 12:00<\/p>\n\n\t\t<\/div>\n\t<\/div>\n<div class=\"vc_empty_space\"   style=\"height: 22px\"><span class=\"vc_empty_space_inner\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid product_wrapper vc_custom_1660494354190 vc_row-has-fill\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_left wpb_content_element  extend_img\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper   vc_box_border_grey\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"900\" src=\"https:\/\/trickshot.ro\/wp-content\/uploads\/2024\/06\/Dessert-2-2.webp\" class=\"vc_single_image-img attachment-full\" alt=\"\" title=\"Dessert 2 (2)\" srcset=\"https:\/\/trickshot.ro\/wp-content\/uploads\/2024\/06\/Dessert-2-2.webp 1600w, https:\/\/trickshot.ro\/wp-content\/uploads\/2024\/06\/Dessert-2-2-300x169.webp 300w, https:\/\/trickshot.ro\/wp-content\/uploads\/2024\/06\/Dessert-2-2-1024x576.webp 1024w, https:\/\/trickshot.ro\/wp-content\/uploads\/2024\/06\/Dessert-2-2-768x432.webp 768w, https:\/\/trickshot.ro\/wp-content\/uploads\/2024\/06\/Dessert-2-2-1536x864.webp 1536w, https:\/\/trickshot.ro\/wp-content\/uploads\/2024\/06\/Dessert-2-2-18x10.webp 18w\" sizes=\"auto, (max-width: 1600px) 100vw, 1600px\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n<div class=\"vc_row wpb_row vc_inner vc_row-fluid vc_custom_1666254753220 vc_row-has-fill\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h2 style=\"font-size: 26px; text-align: center;\"><strong>FOR DESSERT LOVERS<\/strong><\/h2>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div>\n\t<div class=\"wpb_text_column wpb_content_element menu_category_food_desc\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p style=\"text-align: center;\">PREPARATELE SUNT DISPONIBILE \u00ceNCEP\u00c2ND CU ORA 12:00<\/p>\n\n\t\t<\/div>\n\t<\/div>\n<div class=\"vc_empty_space\"   style=\"height: 22px\"><span class=\"vc_empty_space_inner\"><\/span><\/div><\/div><\/div><\/div><\/div><div id=\"meniuri_script\" class=\"vc_row wpb_row vc_row-fluid vc_custom_1664951665949 vc_row-has-fill\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_raw_code wpb_raw_js\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<script> \n<\/script>\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><div id=\"modal_alergeni\" class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-12 vc_col-has-fill\"><div class=\"vc_column-inner vc_custom_1660466468460\"><div class=\"wpb_wrapper\"><div class=\"vc_row wpb_row vc_inner vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-10\"><div class=\"vc_column-inner vc_custom_1660468637329\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h1>Alergeni<\/h1>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"close_modal_icon wpb_column vc_column_container vc_col-sm-2\"><div class=\"vc_column-inner vc_custom_1660496027210\"><div class=\"wpb_wrapper\"><div class=\"vc_icon_element vc_icon_element-outer vc_do_icon vc_icon_element-align-right\"><div class=\"vc_icon_element-inner vc_icon_element-color-custom vc_icon_element-size-md vc_icon_element-style- vc_icon_element-background-color-grey\" ><span class=\"vc_icon_element-icon fas fa-times\" style=\"color:#dd3333 !important\"><\/span><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_inner vc_row-fluid flex-a-center vc_custom_1664954690898 vc_row-has-fill\"><div class=\"width_10 wpb_column vc_column_container vc_col-sm-3\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_left wpb_content_element\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper   vc_box_border_grey\"><img decoding=\"async\" class=\"vc_single_image-img\" src=\"https:\/\/trickshot.ro\/wp-content\/uploads\/2022\/09\/icon_arahide-25x25.png\" width=\"25\" height=\"25\" alt=\"icon_arahide\" title=\"icon_arahide\" loading=\"lazy\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-9\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p>Arahide<\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_inner vc_row-fluid flex-a-center vc_custom_1664954694554 vc_row-has-fill\"><div class=\"width_10 wpb_column vc_column_container vc_col-sm-3\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_left wpb_content_element\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper   vc_box_border_grey\"><img decoding=\"async\" class=\"vc_single_image-img\" src=\"https:\/\/trickshot.ro\/wp-content\/uploads\/2022\/09\/icon_cereale-25x25.png\" width=\"25\" height=\"25\" alt=\"icon_cereale\" title=\"icon_cereale\" loading=\"lazy\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-9\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p>Gluten<\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_inner vc_row-fluid flex-a-center vc_custom_1664954700843 vc_row-has-fill\"><div class=\"width_10 wpb_column vc_column_container vc_col-sm-3\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_left wpb_content_element\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper   vc_box_border_grey\"><img decoding=\"async\" class=\"vc_single_image-img\" src=\"https:\/\/trickshot.ro\/wp-content\/uploads\/2022\/09\/icon_crustacee-25x25.png\" width=\"25\" height=\"25\" alt=\"icon_crustacee\" title=\"icon_crustacee\" loading=\"lazy\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-9\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p>Crustacee<\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_inner vc_row-fluid flex-a-center vc_custom_1664954705225 vc_row-has-fill\"><div class=\"width_10 wpb_column vc_column_container vc_col-sm-3\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_left wpb_content_element\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper   vc_box_border_grey\"><img decoding=\"async\" class=\"vc_single_image-img\" src=\"https:\/\/trickshot.ro\/wp-content\/uploads\/2022\/09\/icon_peste-25x25.png\" width=\"25\" height=\"25\" alt=\"icon_peste\" title=\"icon_peste\" loading=\"lazy\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-9\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p>Pe\u0219te<\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_inner vc_row-fluid flex-a-center vc_custom_1664954709768 vc_row-has-fill\"><div class=\"width_10 wpb_column vc_column_container vc_col-sm-3\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_left wpb_content_element\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper   vc_box_border_grey\"><img decoding=\"async\" class=\"vc_single_image-img\" src=\"https:\/\/trickshot.ro\/wp-content\/uploads\/2022\/09\/icon_soia-25x25.png\" width=\"25\" height=\"25\" alt=\"icon_soia\" title=\"icon_soia\" loading=\"lazy\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-9\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p>Soia<\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_inner vc_row-fluid flex-a-center vc_custom_1664954823675 vc_row-has-fill\"><div class=\"width_10 wpb_column vc_column_container vc_col-sm-3\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_left wpb_content_element\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper   vc_box_border_grey\"><img decoding=\"async\" class=\"vc_single_image-img\" src=\"https:\/\/trickshot.ro\/wp-content\/uploads\/2022\/09\/icon_telina-25x25.png\" width=\"25\" height=\"25\" alt=\"icon_telina\" title=\"icon_telina\" loading=\"lazy\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-9\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p>\u021aelin\u0103<\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_inner vc_row-fluid flex-a-center vc_custom_1664954820386 vc_row-has-fill\"><div class=\"width_10 wpb_column vc_column_container vc_col-sm-3\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_left wpb_content_element\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper   vc_box_border_grey\"><img decoding=\"async\" class=\"vc_single_image-img\" src=\"https:\/\/trickshot.ro\/wp-content\/uploads\/2022\/09\/icon_susan-25x25.png\" width=\"25\" height=\"25\" alt=\"icon_susan\" title=\"icon_susan\" loading=\"lazy\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-9\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p>Susan<\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_inner vc_row-fluid flex-a-center vc_custom_1664954712946 vc_row-has-fill\"><div class=\"width_10 wpb_column vc_column_container vc_col-sm-3\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_left wpb_content_element\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper   vc_box_border_grey\"><img decoding=\"async\" class=\"vc_single_image-img\" src=\"https:\/\/trickshot.ro\/wp-content\/uploads\/2022\/09\/icon_mustar-25x25.png\" width=\"25\" height=\"25\" alt=\"icon_mustar\" title=\"icon_mustar\" loading=\"lazy\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-9\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p>Mu\u0219tar<\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_inner vc_row-fluid flex-a-center vc_custom_1664954732050 vc_row-has-fill\"><div class=\"width_10 wpb_column vc_column_container vc_col-sm-3\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_left wpb_content_element\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper   vc_box_border_grey\"><img decoding=\"async\" class=\"vc_single_image-img\" src=\"https:\/\/trickshot.ro\/wp-content\/uploads\/2022\/09\/icon_oua-25x25.png\" width=\"25\" height=\"25\" alt=\"icon_oua\" title=\"icon_oua\" loading=\"lazy\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-9\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p>Ou\u0103<\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_inner vc_row-fluid flex-a-center vc_custom_1664954769284 vc_row-has-fill\"><div class=\"width_10 wpb_column vc_column_container vc_col-sm-3\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_left wpb_content_element\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper   vc_box_border_grey\"><img decoding=\"async\" class=\"vc_single_image-img\" src=\"https:\/\/trickshot.ro\/wp-content\/uploads\/2022\/09\/icon_nuci-si-alune-25x25.png\" width=\"25\" height=\"25\" alt=\"icon_nuci si alune\" title=\"icon_nuci si alune\" loading=\"lazy\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-9\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p>Nuci \u0219i alune<\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_inner vc_row-fluid flex-a-center vc_custom_1664954775910 vc_row-has-fill\"><div class=\"width_10 wpb_column vc_column_container vc_col-sm-3\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_left wpb_content_element\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper   vc_box_border_grey\"><img decoding=\"async\" class=\"vc_single_image-img\" src=\"https:\/\/trickshot.ro\/wp-content\/uploads\/2022\/09\/icon_lupin-25x25.png\" width=\"25\" height=\"25\" alt=\"icon_lupin\" title=\"icon_lupin\" loading=\"lazy\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-9\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p>Lupin<\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_inner vc_row-fluid flex-a-center vc_custom_1664954779289 vc_row-has-fill\"><div class=\"width_10 wpb_column vc_column_container vc_col-sm-3\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_left wpb_content_element\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper   vc_box_border_grey\"><img decoding=\"async\" class=\"vc_single_image-img\" src=\"https:\/\/trickshot.ro\/wp-content\/uploads\/2022\/09\/icon_moluste-25x25.png\" width=\"25\" height=\"25\" alt=\"icon_moluste\" title=\"icon_moluste\" loading=\"lazy\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-9\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p>Molu\u0219te<\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_inner vc_row-fluid flex-a-center vc_custom_1664954783220 vc_row-has-fill\"><div class=\"width_10 wpb_column vc_column_container vc_col-sm-3\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_left wpb_content_element\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper   vc_box_border_grey\"><img decoding=\"async\" class=\"vc_single_image-img\" src=\"https:\/\/trickshot.ro\/wp-content\/uploads\/2022\/09\/icon_lapte-25x25.png\" width=\"25\" height=\"25\" alt=\"icon_lapte\" title=\"icon_lapte\" loading=\"lazy\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-9\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p>Lapte<\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_inner vc_row-fluid flex-a-center vc_custom_1664954783220 vc_row-has-fill\"><div class=\"width_10 wpb_column vc_column_container vc_col-sm-3\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_left wpb_content_element\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper   vc_box_border_grey\"><img decoding=\"async\" class=\"vc_single_image-img\" src=\"https:\/\/trickshot.ro\/wp-content\/uploads\/2023\/04\/icon-sulfiti3-25x25.png\" width=\"25\" height=\"25\" alt=\"icon-sulfiti3\" title=\"icon-sulfiti3\" loading=\"lazy\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-9\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p>Sulfi\u021bi<\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><div class=\"vc_empty_space\"   style=\"height: 32px\"><span class=\"vc_empty_space_inner\"><\/span><\/div><\/div><\/div><\/div><\/div><div id=\"modal_dieta\" class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-12 vc_col-has-fill\"><div class=\"vc_column-inner vc_custom_1660466468460\"><div class=\"wpb_wrapper\"><div class=\"vc_row wpb_row vc_inner vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-10\"><div class=\"vc_column-inner vc_custom_1660468637329\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h1>Diet\u0103<\/h1>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"close_modal_icon wpb_column vc_column_container vc_col-sm-2\"><div class=\"vc_column-inner vc_custom_1660496027210\"><div class=\"wpb_wrapper\"><div class=\"vc_icon_element vc_icon_element-outer vc_do_icon vc_icon_element-align-right\"><div class=\"vc_icon_element-inner vc_icon_element-color-custom vc_icon_element-size-md vc_icon_element-style- vc_icon_element-background-color-grey\" ><span class=\"vc_icon_element-icon fas fa-times\" style=\"color:#dd3333 !important\"><\/span><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_inner vc_row-fluid flex-a-center vc_custom_1664954690898 vc_row-has-fill\"><div class=\"width_10 wpb_column vc_column_container vc_col-sm-3\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_left wpb_content_element\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper   vc_box_border_grey\"><img decoding=\"async\" class=\"vc_single_image-img\" src=\"https:\/\/trickshot.ro\/wp-content\/uploads\/2022\/09\/icon_lacto-ovo-vegetarian--25x25.png\" width=\"25\" height=\"25\" alt=\"icon_lacto-ovo-vegetarian\" title=\"icon_lacto-ovo-vegetarian\" loading=\"lazy\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-9\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p>Lacto-ovo-vegetarian<\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_inner vc_row-fluid flex-a-center vc_custom_1664954690898 vc_row-has-fill\"><div class=\"width_10 wpb_column vc_column_container vc_col-sm-3\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_left wpb_content_element\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper   vc_box_border_grey\"><img decoding=\"async\" class=\"vc_single_image-img\" src=\"https:\/\/trickshot.ro\/wp-content\/uploads\/2022\/09\/icon_lacto-vegetarian--25x25.png\" width=\"25\" height=\"25\" alt=\"icon_lacto-vegetarian\" title=\"icon_lacto-vegetarian\" loading=\"lazy\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-9\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p>Lacto-vegetarian<\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_inner vc_row-fluid flex-a-center vc_custom_1664954690898 vc_row-has-fill\"><div class=\"width_10 wpb_column vc_column_container vc_col-sm-3\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_left wpb_content_element\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper   vc_box_border_grey\"><img decoding=\"async\" class=\"vc_single_image-img\" src=\"https:\/\/trickshot.ro\/wp-content\/uploads\/2022\/09\/icon_vegetarian-25x25.png\" width=\"25\" height=\"25\" alt=\"icon_vegetarian\" title=\"icon_vegetarian\" loading=\"lazy\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-9\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p>Vegetarian<\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><div class=\"vc_empty_space\"   style=\"height: 32px\"><span class=\"vc_empty_space_inner\"><\/span><\/div><\/div><\/div><\/div><\/div><div id=\"modal_contact\" class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-12 vc_col-has-fill\"><div class=\"vc_column-inner vc_custom_1660466468460\"><div class=\"wpb_wrapper\"><div class=\"vc_row wpb_row vc_inner vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-10\"><div class=\"vc_column-inner vc_custom_1660468637329\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h1>Contact<\/h1>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"close_modal_icon wpb_column vc_column_container vc_col-sm-2\"><div class=\"vc_column-inner vc_custom_1660496027210\"><div class=\"wpb_wrapper\"><div class=\"vc_icon_element vc_icon_element-outer vc_do_icon vc_icon_element-align-right\"><div class=\"vc_icon_element-inner vc_icon_element-color-custom vc_icon_element-size-md vc_icon_element-style- vc_icon_element-background-color-grey\" ><span class=\"vc_icon_element-icon fas fa-times\" style=\"color:#dd3333 !important\"><\/span><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_inner vc_row-fluid vc_custom_1660468058392 vc_row-has-fill\"><div class=\"wpb_column vc_column_container vc_col-sm-1\/5 vc_col-xs-1\/5\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"vc_icon_element vc_icon_element-outer vc_do_icon vc_icon_element-align-left\"><div class=\"vc_icon_element-inner vc_icon_element-color-blue vc_icon_element-size-md vc_icon_element-style- vc_icon_element-background-color-grey\" ><span class=\"vc_icon_element-icon fas fa-map-marker-alt\" ><\/span><a class=\"vc_icon_element-link\" href=\"https:\/\/www.google.com\/maps\/place\/trickSHOT+Promenada\/@44.4785652,26.0983304,17z\/data=!3m2!4b1!5s0x40b202709dd9d68d:0x8539bf0eb9838d85!4m6!3m5!1s0x40b202709e8ae1a9:0x32c176e60a4e2a7d!8m2!3d44.4785615!4d26.1028151!16s%2Fg%2F11cmsqxmv0\"  title=\"\" target=\"_self\"><\/a><\/div><\/div><\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-4\/5\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p>Calea Floreasca 246B, Bucharest<\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_inner vc_row-fluid vc_custom_1660468058392 vc_row-has-fill\"><div class=\"wpb_column vc_column_container vc_col-sm-1\/5 vc_col-xs-1\/5\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"vc_icon_element vc_icon_element-outer vc_do_icon vc_icon_element-align-left\"><div class=\"vc_icon_element-inner vc_icon_element-color-blue vc_icon_element-size-md vc_icon_element-style- vc_icon_element-background-color-grey\" ><span class=\"vc_icon_element-icon fas fa-phone\" ><\/span><a class=\"vc_icon_element-link\" href=\"tel:0756%20143%20303\"  title=\"\" target=\"_self\"><\/a><\/div><\/div><\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-4\/5\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p>031 005 2750<\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_inner vc_row-fluid vc_custom_1660468058392 vc_row-has-fill\"><div class=\"wpb_column vc_column_container vc_col-sm-1\/5 vc_col-xs-1\/5\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"vc_icon_element vc_icon_element-outer vc_do_icon vc_icon_element-align-left\"><div class=\"vc_icon_element-inner vc_icon_element-color-blue vc_icon_element-size-md vc_icon_element-style- vc_icon_element-background-color-grey\" ><span class=\"vc_icon_element-icon fab fa-facebook-square\" ><\/span><a class=\"vc_icon_element-link\" href=\"https:\/\/www.facebook.com\/trickSHOTpromenada\/\"  title=\"\" target=\"_self\"><\/a><\/div><\/div><\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-4\/5\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p>Facebook<\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_inner vc_row-fluid vc_custom_1660468058392 vc_row-has-fill\"><div class=\"wpb_column vc_column_container vc_col-sm-1\/5 vc_col-xs-1\/5\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"vc_icon_element vc_icon_element-outer vc_do_icon vc_icon_element-align-left\"><div class=\"vc_icon_element-inner vc_icon_element-color-blue vc_icon_element-size-md vc_icon_element-style- vc_icon_element-background-color-grey\" ><span class=\"vc_icon_element-icon fab fa-instagram\" ><\/span><a class=\"vc_icon_element-link\" href=\"https:\/\/www.instagram.com\/trickshotrestaurants\/\"  title=\"\" target=\"_self\"><\/a><\/div><\/div><\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-4\/5\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p>Instagram<\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><div class=\"vc_empty_space\"   style=\"height: 32px\"><span class=\"vc_empty_space_inner\"><\/span><\/div><\/div><\/div><\/div><\/div><div id=\"modal_social\" class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-12 vc_col-has-fill\"><div class=\"vc_column-inner vc_custom_1660466468460\"><div class=\"wpb_wrapper\"><div class=\"vc_row wpb_row vc_inner vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-10\"><div class=\"vc_column-inner vc_custom_1660468637329\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h1>Distribuie meniul<\/h1>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"close_modal_icon wpb_column vc_column_container vc_col-sm-2\"><div class=\"vc_column-inner vc_custom_1660496027210\"><div class=\"wpb_wrapper\"><div class=\"vc_icon_element vc_icon_element-outer vc_do_icon vc_icon_element-align-right\"><div class=\"vc_icon_element-inner vc_icon_element-color-custom vc_icon_element-size-md vc_icon_element-style- vc_icon_element-background-color-grey\" ><span class=\"vc_icon_element-icon fas fa-times\" style=\"color:#dd3333 !important\"><\/span><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_inner vc_row-fluid vc_custom_1660468058392 vc_row-has-fill\"><div class=\"wpb_column vc_column_container vc_col-sm-1\/5 vc_col-xs-1\/5\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"vc_icon_element vc_icon_element-outer vc_do_icon vc_icon_element-align-left\"><div class=\"vc_icon_element-inner vc_icon_element-color-blue vc_icon_element-size-md vc_icon_element-style- vc_icon_element-background-color-grey\" ><span class=\"vc_icon_element-icon fab fa-facebook-square\" ><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-4\/5\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p>Facebook<\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_inner vc_row-fluid vc_custom_1660468058392 vc_row-has-fill\"><div class=\"wpb_column vc_column_container vc_col-sm-1\/5 vc_col-xs-1\/5\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"vc_icon_element vc_icon_element-outer vc_do_icon vc_icon_element-align-left\"><div class=\"vc_icon_element-inner vc_icon_element-color-green vc_icon_element-size-md vc_icon_element-style- vc_icon_element-background-color-grey\" ><span class=\"vc_icon_element-icon fab fa-whatsapp\" ><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-4\/5\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p>WhatsApp<\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_inner vc_row-fluid vc_custom_1660468058392 vc_row-has-fill\"><div class=\"wpb_column vc_column_container vc_col-sm-1\/5 vc_col-xs-1\/5\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"vc_icon_element vc_icon_element-outer vc_do_icon vc_icon_element-align-left\"><div class=\"vc_icon_element-inner vc_icon_element-color-turquoise vc_icon_element-size-md vc_icon_element-style- vc_icon_element-background-color-grey\" ><span class=\"vc_icon_element-icon far fa-envelope\" ><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-4\/5\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p>Mail<\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><div class=\"vc_empty_space\"   style=\"height: 32px\"><span class=\"vc_empty_space_inner\"><\/span><\/div><\/div><\/div><\/div><\/div><div id=\"meniu_footer\" data-vc-full-width=\"true\" data-vc-full-width-temp=\"true\" data-vc-full-width-init=\"false\" class=\"vc_row wpb_row vc_row-fluid vc_custom_1660481490043 vc_row-has-fill\"><div class=\"width_20 wpb_column vc_column_container vc_col-sm-6\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"vc_icon_element vc_icon_element-outer vc_do_icon vc_icon_element-align-center\"><div class=\"vc_icon_element-inner vc_icon_element-color-custom vc_icon_element-size-md vc_icon_element-style- vc_icon_element-background-color-grey\" ><span class=\"vc_icon_element-icon fas fa-home\" style=\"color:#1f1f1f !important\"><\/span><a class=\"vc_icon_element-link\" href=\"https:\/\/trickshot.ro\/en\/menu\/\"  title=\"Meniuri\" target=\"_self\"><\/a><\/div><\/div>\n\t<div class=\"wpb_text_column wpb_content_element footer_icon_text\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p style=\"text-align: center;\">Home<\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"width_20 wpb_column vc_column_container vc_col-sm-6\" id=\"footer_button_info\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"vc_icon_element vc_icon_element-outer vc_do_icon vc_icon_element-align-center\"><div class=\"vc_icon_element-inner vc_icon_element-color-custom vc_icon_element-size-md vc_icon_element-style- vc_icon_element-background-color-grey\" ><span class=\"vc_icon_element-icon fas fa-info\" style=\"color:#1f1f1f !important\"><\/span><\/div><\/div>\n\t<div class=\"wpb_text_column wpb_content_element footer_icon_text\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p style=\"text-align: center;\">Info<\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><div class=\"vc_row-full-width vc_clearfix\"><\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"\ud83c\udf31Responsabilitate fa\u021b\u0103 de m\u00e2ncare: 1\/3 din m\u00e2ncarea produs\u0103 \u00een lume este irosit\u0103. Asta \u00eenseamn\u0103 peste 1,3 miliarde de tone de alimente \u00een fiecare an. \u00cen Rom\u00e2nia, risipa alimentar\u0103 dep\u0103\u0219e\u0219te 2,2 milioane de tone anual, aproximativ 129 kg de m\u00e2ncare irosit\u0103 de fiecare persoan\u0103 \u00een fiecare an. La TRICKSHOT credem c\u0103 [...]","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-7486","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/trickshot.ro\/en\/wp-json\/wp\/v2\/pages\/7486","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/trickshot.ro\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/trickshot.ro\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/trickshot.ro\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/trickshot.ro\/en\/wp-json\/wp\/v2\/comments?post=7486"}],"version-history":[{"count":16,"href":"https:\/\/trickshot.ro\/en\/wp-json\/wp\/v2\/pages\/7486\/revisions"}],"predecessor-version":[{"id":9320,"href":"https:\/\/trickshot.ro\/en\/wp-json\/wp\/v2\/pages\/7486\/revisions\/9320"}],"wp:attachment":[{"href":"https:\/\/trickshot.ro\/en\/wp-json\/wp\/v2\/media?parent=7486"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}